{"id":93,"count":1,"description":"","link":"https:\/\/blogs.gre.ac.uk\/greengreenwich\/tag\/cherries\/","name":"cherries","slug":"cherries","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.gre.ac.uk\/greengreenwich\/wp-json\/wp\/v2\/tags\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.gre.ac.uk\/greengreenwich\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.gre.ac.uk\/greengreenwich\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.gre.ac.uk\/greengreenwich\/wp-json\/wp\/v2\/posts?tags=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}